{"id":6340,"date":"2025-11-11T09:58:21","date_gmt":"2025-11-11T14:58:21","guid":{"rendered":"https:\/\/www.kalkalaw.com\/blog\/el-estatuto-de-muerte-por-negligencia-de-georgia-lo-que-las-familias-deben-saber\/"},"modified":"2025-11-11T09:58:21","modified_gmt":"2025-11-11T14:58:21","slug":"el-estatuto-de-muerte-por-negligencia-de-georgia-lo-que-las-familias-deben-saber","status":"publish","type":"post","link":"https:\/\/www.kalkalaw.com\/es\/blog\/el-estatuto-de-muerte-por-negligencia-de-georgia-lo-que-las-familias-deben-saber\/","title":{"rendered":"El Estatuto de Muerte por Negligencia de Georgia: Lo que las familias deben saber"},"content":{"rendered":"<p>Perder a un ser querido por la negligencia o los actos il\u00edcitos de otra persona es una experiencia devastadora. La ley de Georgia sobre homicidio culposo ofrece a los familiares supervivientes una v\u00eda legal para reclamar una indemnizaci\u00f3n por su p\u00e9rdida y por el sufrimiento que pudiera haber padecido el fallecido. Sin embargo, navegar por el proceso legal puede resultar abrumador. Entender c\u00f3mo funcionan las leyes de muerte por negligencia de Georgia es esencial para que las familias se aseguren de recibir la indemnizaci\u00f3n que merecen.   <\/p>\n<p>Este art\u00edculo ofrece un desglose exhaustivo de la ley de muerte por negligencia de Georgia, incluyendo qui\u00e9n puede presentar una demanda, qu\u00e9 da\u00f1os pueden recuperarse y c\u00f3mo funciona el proceso legal.<\/p>\n<h2>\u00bfQu\u00e9 es la Ley de Muerte por Negligencia de Georgia?<\/h2>\n<p>La ley de Georgia sobre homicidio culposo, codificada en O.C.G.A. \u00a7\u00a7 51-4-1 &#8211; 51-4-6, permite a los familiares reclamar da\u00f1os y perjuicios cuando un ser querido fallece debido a la negligencia o las acciones il\u00edcitas de otra parte. La ley divide las demandas por homicidio culposo en dos componentes: la demanda por homicidio culposo y la demanda de sucesi\u00f3n. <\/p>\n<ol>\n<li>Demanda por homicidio culposo: Esta demanda la presenta el pariente m\u00e1s cercano (c\u00f3nyuge, hijos, etc.) para reclamar da\u00f1os y perjuicios por la p\u00e9rdida de la vida del fallecido. La demanda por homicidio culposo se centra en el valor de la vida del fallecido, incluidos los da\u00f1os econ\u00f3micos (salarios perdidos) y no econ\u00f3micos (p\u00e9rdida de compa\u00f1\u00eda, amor y apoyo). <\/li>\n<li>Reclamaci\u00f3n patrimonial: Esta reclamaci\u00f3n la presenta la sucesi\u00f3n del fallecido y se refiere al sufrimiento previo a la muerte del propio fallecido, las facturas m\u00e9dicas, los gastos funerarios y el dolor y sufrimiento.<\/li>\n<\/ol>\n<p>Estas dos reclamaciones son independientes, con procedimientos distintos. Aunque la familia puede actuar como administrador de la herencia, las reclamaciones por homicidio culposo y por herencia se tratan por separado seg\u00fan la ley de Georgia. <\/p>\n<h2>\u00bfQui\u00e9n puede presentar una demanda por homicidio culposo en Georgia?<\/h2>\n<p>O.C.G.A. \u00a7 51-4-2 especifica qui\u00e9n puede presentar una demanda por homicidio culposo. La ley establece un claro orden de prioridad: <\/p>\n<ol>\n<li>C\u00f3nyuge superviviente: Si al fallecido le sobrevive un c\u00f3nyuge, \u00e9ste presenta la demanda por homicidio culposo en su propio nombre y en el de sus hijos. El c\u00f3nyuge debe compartir la indemnizaci\u00f3n con los hijos, pero debe recibir al menos un tercio de la indemnizaci\u00f3n total, tal como se especifica en O.C.G.A. \u00a7 51-4-2(c). <\/li>\n<li>Hijos supervivientes: Si no hay c\u00f3nyuge superviviente, los hijos pueden presentar la demanda por homicidio culposo.<\/li>\n<li>Padres supervivientes: Si no hay c\u00f3nyuge ni hijos supervivientes, los padres del difunto pueden presentar la demanda.<\/li>\n<li>Administrador o albacea de la herencia: Si no hay c\u00f3nyuge, hijos o padres supervivientes, el administrador o albacea de la herencia del difunto puede presentar la demanda por homicidio culposo en nombre de los parientes m\u00e1s pr\u00f3ximos, seg\u00fan las leyes de sucesi\u00f3n intestada de Georgia.<\/li>\n<\/ol>\n<p>Es importante tener en cuenta que los hermanos no tienen derecho a presentar directamente una demanda por homicidio culposo, ya que la ley no les concede el derecho principal a presentar la demanda por s\u00ed mismos. Sin embargo, en ausencia de c\u00f3nyuge superviviente, hijos o padres, los hermanos pueden recibir en \u00faltima instancia los fondos recuperados, pero la demanda debe presentarla el administrador o albacea de la herencia, no los propios hermanos. <\/p>\n<h3>Un ejemplo clarificador<\/h3>\n<p>Es importante tener en cuenta que la ley especifica un orden de prioridad distinto en caso de fallecimiento de un hijo (seg\u00fan O.C.G.A. \u00a7 51-4-4). En esa situaci\u00f3n concreta, los padres supervivientes tienen el derecho principal a presentar la demanda. <\/p>\n<p>Por ejemplo, si una madre perdiera a sus dos hijos en un tr\u00e1gico accidente, presentar\u00eda la demanda por homicidio culposo en nombre de los hijos. Sin embargo, si el padre de los hijos siguiera vivo, ambos progenitores presentar\u00edan conjuntamente la demanda. La reclamaci\u00f3n de la herencia se tramitar\u00eda por separado, y ser\u00eda la herencia, y no la madre, quien presentar\u00eda esa reclamaci\u00f3n por las facturas m\u00e9dicas y los gastos funerarios de los hijos.  <\/p>\n<h2>\u00bfQu\u00e9 da\u00f1os y perjuicios pueden reclamarse en un caso de homicidio culposo?<\/h2>\n<p>En un caso de homicidio culposo en Georgia, pueden recuperarse tanto los da\u00f1os econ\u00f3micos como los no econ\u00f3micos. La indemnizaci\u00f3n por muerte <a href=\"https:\/\/www.kalkalaw.com\/blog\/average-wrongful-death-lawsuit-settlement-payout-georgia-payout-for-medical-negligence-resulting-in-death\/\">por negligencia<\/a> compensa el valor de la vida, que incluye tanto las p\u00e9rdidas tangibles como las intangibles. <\/p>\n<ul>\n<li>Da\u00f1os econ\u00f3micos: Incluyen los salarios futuros perdidos por el difunto y la ayuda econ\u00f3mica que hubiera prestado a su familia.<\/li>\n<li>Da\u00f1os no econ\u00f3micos: Se refieren a las p\u00e9rdidas intangibles que han sufrido los supervivientes, como la p\u00e9rdida de compa\u00f1\u00eda, cuidados y apoyo emocional.<\/li>\n<\/ul>\n<p>Es importante tener en cuenta que la p\u00e9rdida de consorcio (la p\u00e9rdida de compa\u00f1\u00eda, servicios, etc.) no es una reclamaci\u00f3n independiente en los casos de muerte por negligencia de Georgia. En cambio, forma parte de la reclamaci\u00f3n por \u00abvalor total de la vida\u00bb. Las familias no pueden presentar a la vez una demanda por homicidio culposo y una demanda separada por p\u00e9rdida de consorcio. Todos los aspectos de la p\u00e9rdida, incluida la p\u00e9rdida de compa\u00f1\u00eda y el sufrimiento emocional, se incluyen en la propia demanda por homicidio culposo.   <\/p>\n<p>La reclamaci\u00f3n patrimonial es distinta y cubre da\u00f1os como el dolor y el sufrimiento del difunto antes de morir, as\u00ed como las facturas m\u00e9dicas y los gastos funerarios en que haya incurrido.<\/p>\n<h2>\u00bfPuedes pedir da\u00f1os punitivos en un caso de homicidio culposo?<\/h2>\n<p>Los da\u00f1os punitivos s\u00f3lo pueden solicitarse en determinadas circunstancias y s\u00f3lo son recuperables a trav\u00e9s de la reclamaci\u00f3n patrimonial, no de la reclamaci\u00f3n principal por homicidio culposo.<\/p>\n<p>En Georgia, los da\u00f1os punitivos tienen por objeto castigar conductas especialmente atroces y disuadir de futuras fechor\u00edas. Por ejemplo, si la muerte del difunto fue consecuencia de un accidente por conducir bajo los efectos del alcohol o de un defecto de un producto, pueden concederse da\u00f1os punitivos si las acciones del acusado fueron especialmente imprudentes o malintencionadas. <\/p>\n<p>Sin embargo, los da\u00f1os punitivos no est\u00e1n disponibles en la propia demanda por homicidio culposo, que se limita a buscar una indemnizaci\u00f3n por el \u00abvalor total de la vida\u00bb. Los da\u00f1os punitivos s\u00f3lo pueden perseguirse mediante la reclamaci\u00f3n patrimonial (que cubre el sufrimiento del difunto antes de morir), como cuando el difunto padeci\u00f3 dolor o angustia importantes antes de morir. <\/p>\n<h3>L\u00edmite de da\u00f1os punitivos en Georgia<\/h3>\n<p>En la mayor\u00eda de los casos, la ley de Georgia impone un l\u00edmite de 250.000 $ a los da\u00f1os punitivos, seg\u00fan O.C.G.A. \u00a7 51-12-5.1. Sin embargo, este tope tiene excepciones. Si el acusado estaba bajo los efectos de las drogas o el alcohol, o actu\u00f3 con la intenci\u00f3n espec\u00edfica de da\u00f1ar al difunto, no se aplica ning\u00fan l\u00edmite, y pueden concederse da\u00f1os punitivos sin limitaci\u00f3n.  <\/p>\n<p>Adem\u00e1s, en los casos de responsabilidad por productos defectuosos, el 75% de los da\u00f1os punitivos concedidos (una vez deducidos los honorarios razonables de los abogados y los costes del litigio) deben abonarse al Tesoro P\u00fablico, y el demandante recibe el 25% restante.<\/p>\n<h2>El plazo de prescripci\u00f3n: Por qu\u00e9 es importante el tiempo<\/h2>\n<p>En Georgia, el plazo de prescripci\u00f3n para presentar una demanda por homicidio culposo es de dos a\u00f1os a partir de la fecha de fallecimiento del difunto, seg\u00fan se establece en O.C.G.A. \u00a7 9-3-33. Sin embargo, hay excepciones, como cuando hay una causa penal de por medio, que pueden hacer que prescriba (pausar) el plazo de prescripci\u00f3n hasta que se resuelva la causa penal. <\/p>\n<p>Retrasar la presentaci\u00f3n de una demanda puede hacer que la familia pierda aspectos cruciales del caso, como el resarcimiento de da\u00f1os y perjuicios por dolor y sufrimiento o facturas m\u00e9dicas. Por ejemplo, si la muerte por negligencia fue causada por un incendio dom\u00e9stico, la familia podr\u00eda perder la oportunidad de recuperar el dolor y el sufrimiento del difunto si se retrasa la reclamaci\u00f3n. <\/p>\n<h2>El proceso judicial: Qu\u00e9 esperar<\/h2>\n<p>El proceso para presentar una demanda por homicidio culposo comienza con el nombramiento de un administrador o albacea de la herencia del difunto. Esta persona gestionar\u00e1 la reclamaci\u00f3n patrimonial y se asegurar\u00e1 de que se pagan las facturas m\u00e9dicas, los gastos funerarios y otras deudas antes de distribuir los fondos a la familia. <\/p>\n<p>Una vez nombrado el administrador, la <a href=\"https:\/\/www.kalkalaw.com\/lawrenceville-wrongful-death-lawyer-near-you\/\">demanda por homicidio culposo<\/a> se presenta en el condado correspondiente, que suele ser el condado donde reside el demandado o donde ocurri\u00f3 el accidente. Si en el siniestro estuvo implicada una empresa (por ejemplo, una empresa de camiones), la demanda puede presentarse donde est\u00e9 registrada la empresa. <\/p>\n<p>En casos complejos, como uno en el que un accidente de cami\u00f3n provoca m\u00faltiples muertes, es crucial identificar a los familiares correctos y asegurarse de que todas las reclamaciones necesarias se presentan adecuadamente. El administrador o albacea desempe\u00f1a un papel clave en la gesti\u00f3n de estas reclamaciones y en garantizar la protecci\u00f3n de los intereses de la familia. <\/p>\n<h2>Tipos de accidentes que dan lugar a demandas por homicidio culposo<\/h2>\n<p>Las demandas por homicidio culposo pueden derivarse de diversos accidentes, entre ellos:<\/p>\n<ul>\n<li>Accidentes de tr\u00e1fico: Conducci\u00f3n negligente o temeraria, como el exceso de velocidad o la conducci\u00f3n bajo los efectos del alcohol.<\/li>\n<li>Accidentes de cami\u00f3n: Colisiones en las que est\u00e1n implicados grandes camiones, sobre todo las causadas por negligencia o fatiga del conductor.<\/li>\n<li>Accidentes relacionados con el alcohol: Casos de alcoholismo, en los que los bares sirven demasiado a los clientes, o accidentes causados por conductores ebrios.<\/li>\n<li>Accidentes de navegaci\u00f3n: Especialmente los relacionados con el alcohol, en los que la falta de medidas de seguridad provoca v\u00edctimas mortales.<\/li>\n<li>Accidentes en la construcci\u00f3n: En algunos casos, los trabajadores pueden presentar tanto una demanda de indemnizaci\u00f3n por accidente laboral como una demanda por da\u00f1os personales contra un tercero.<\/li>\n<\/ul>\n<h3>Gesti\u00f3n de siniestros m\u00faltiples: Indemnizaci\u00f3n Laboral y Reclamaciones a Terceros<\/h3>\n<p>En algunos casos, una demanda por homicidio culposo puede ir acompa\u00f1ada de una demanda de indemnizaci\u00f3n por accidente laboral, sobre todo en los fallecimientos relacionados con el lugar de trabajo. Si el fallecido muri\u00f3 a causa de un accidente laboral, su familia puede tener derecho a presentar una reclamaci\u00f3n de indemnizaci\u00f3n laboral por gastos m\u00e9dicos y salarios perdidos. Adem\u00e1s, si un tercero (como un contratista o proveedor) fue responsable del accidente, la familia puede presentar una demanda por da\u00f1os personales o muerte por negligencia contra esa parte.  <\/p>\n<p>Las familias preguntan a menudo: \u00ab<a href=\"https:\/\/www.kalkalaw.com\/es\/blog\/puedes-presentar-una-demanda-por-lesiones-laborales-y-una-demanda-por-lesiones-personales-en-georgia-demandar-a-la-compensacion-a-los-trabajadores\/\">\u00bfSe puede presentar una demanda de compensaci\u00f3n de trabajadores y otra de da\u00f1os personales?<\/a>\u00ab. En Georgia, no puedes demandar al empresario si se aplica la compensaci\u00f3n de los trabajadores, pero puedes presentar una demanda separada por lesiones personales o muerte por negligencia contra un tercero negligente, adem\u00e1s del caso de compensaci\u00f3n de los trabajadores.<\/p>\n<h2>C\u00f3mo puede ayudar Kalka Law Group<\/h2>\n<p>En Kalka Law Group, nuestros <a href=\"https:\/\/www.kalkalaw.com\/personal-injury\/wrongful-death-lawyers-marietta-ga-personal-injury-lawyer-near-you\/\">abogados especializados en lesiones personales<\/a> comprenden la abrumadora pena y el estr\u00e9s que conlleva la p\u00e9rdida de un ser querido. Nos comprometemos a ocuparnos de todos los aspectos del proceso de homicidio culposo, desde la designaci\u00f3n del administrador de la herencia adecuado hasta la presentaci\u00f3n de las demandas tanto por homicidio culposo como por sucesi\u00f3n. Nuestro equipo se dedica a conseguir la indemnizaci\u00f3n que te mereces, al tiempo que permite a tu familia centrarse en la curaci\u00f3n.  <\/p>\n<p>Si has perdido a un ser querido debido a la negligencia o las acciones il\u00edcitas de otra persona, nuestros <a href=\"https:\/\/www.kalkalaw.com\/wrongful-death-lawyer-atlanta-georgia-personal-injury-lawyer-near-me\/\">abogados especializados en homicidio culposo<\/a> de Kalka Law Group est\u00e1n aqu\u00ed para ayudarte a guiarte a trav\u00e9s del proceso legal y proteger tus derechos. Perm\u00edtenos ayudarte a buscar justicia y garantizar que tu familia reciba la indemnizaci\u00f3n necesaria para seguir adelante. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Perder a un ser querido por la negligencia o los [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[97],"tags":[],"class_list":["post-6340","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Explicaci\u00f3n de la Ley de Homicidio Culposo de Georgia | Kalka Law Group<\/title>\n<meta name=\"description\" content=\"Ent\u00e9rate de c\u00f3mo funciona la ley de Georgia sobre homicidio culposo, qui\u00e9n puede presentar una demanda, de qu\u00e9 da\u00f1os y perjuicios se dispone y los plazos para demandar tras la muerte de un ser querido.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kalkalaw.com\/es\/blog\/el-estatuto-de-muerte-por-negligencia-de-georgia-lo-que-las-familias-deben-saber\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Explicaci\u00f3n de la Ley de Homicidio Culposo de Georgia | Kalka Law Group\" \/>\n<meta property=\"og:description\" content=\"Ent\u00e9rate de c\u00f3mo funciona la ley de Georgia sobre homicidio culposo, qui\u00e9n puede presentar una demanda, de qu\u00e9 da\u00f1os y perjuicios se dispone y los plazos para demandar tras la muerte de un ser querido.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kalkalaw.com\/es\/blog\/el-estatuto-de-muerte-por-negligencia-de-georgia-lo-que-las-familias-deben-saber\/\" \/>\n<meta property=\"og:site_name\" content=\"The Kalka Law Group - Personal Injury &amp; Car Accident Attorneys\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KalkaLawGroup\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-11T14:58:21+00:00\" \/>\n<meta name=\"author\" content=\"Kalka Law\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KalkaLawGroup\" \/>\n<meta name=\"twitter:site\" content=\"@KalkaLawGroup\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kalka Law\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Explicaci\u00f3n de la Ley de Homicidio Culposo de Georgia | Kalka Law Group","description":"Ent\u00e9rate de c\u00f3mo funciona la ley de Georgia sobre homicidio culposo, qui\u00e9n puede presentar una demanda, de qu\u00e9 da\u00f1os y perjuicios se dispone y los plazos para demandar tras la muerte de un ser querido.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kalkalaw.com\/es\/blog\/el-estatuto-de-muerte-por-negligencia-de-georgia-lo-que-las-familias-deben-saber\/","og_locale":"es_ES","og_type":"article","og_title":"Explicaci\u00f3n de la Ley de Homicidio Culposo de Georgia | Kalka Law Group","og_description":"Ent\u00e9rate de c\u00f3mo funciona la ley de Georgia sobre homicidio culposo, qui\u00e9n puede presentar una demanda, de qu\u00e9 da\u00f1os y perjuicios se dispone y los plazos para demandar tras la muerte de un ser querido.","og_url":"https:\/\/www.kalkalaw.com\/es\/blog\/el-estatuto-de-muerte-por-negligencia-de-georgia-lo-que-las-familias-deben-saber\/","og_site_name":"The Kalka Law Group - Personal Injury &amp; Car Accident Attorneys","article_publisher":"https:\/\/www.facebook.com\/KalkaLawGroup\/","article_published_time":"2025-11-11T14:58:21+00:00","author":"Kalka Law","twitter_card":"summary_large_image","twitter_creator":"@KalkaLawGroup","twitter_site":"@KalkaLawGroup","twitter_misc":{"Escrito por":"Kalka Law","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kalkalaw.com\/es\/blog\/el-estatuto-de-muerte-por-negligencia-de-georgia-lo-que-las-familias-deben-saber\/#article","isPartOf":{"@id":"https:\/\/www.kalkalaw.com\/es\/blog\/el-estatuto-de-muerte-por-negligencia-de-georgia-lo-que-las-familias-deben-saber\/"},"author":{"name":"Kalka Law","@id":"https:\/\/www.kalkalaw.com\/es\/#\/schema\/person\/bcee12dd478c67036469886a7b9fdb26"},"headline":"El Estatuto de Muerte por Negligencia de Georgia: Lo que las familias deben saber","datePublished":"2025-11-11T14:58:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kalkalaw.com\/es\/blog\/el-estatuto-de-muerte-por-negligencia-de-georgia-lo-que-las-familias-deben-saber\/"},"wordCount":2086,"publisher":{"@id":"https:\/\/www.kalkalaw.com\/es\/#organization"},"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.kalkalaw.com\/es\/blog\/el-estatuto-de-muerte-por-negligencia-de-georgia-lo-que-las-familias-deben-saber\/","url":"https:\/\/www.kalkalaw.com\/es\/blog\/el-estatuto-de-muerte-por-negligencia-de-georgia-lo-que-las-familias-deben-saber\/","name":"Explicaci\u00f3n de la Ley de Homicidio Culposo de Georgia | Kalka Law Group","isPartOf":{"@id":"https:\/\/www.kalkalaw.com\/es\/#website"},"datePublished":"2025-11-11T14:58:21+00:00","description":"Ent\u00e9rate de c\u00f3mo funciona la ley de Georgia sobre homicidio culposo, qui\u00e9n puede presentar una demanda, de qu\u00e9 da\u00f1os y perjuicios se dispone y los plazos para demandar tras la muerte de un ser querido.","breadcrumb":{"@id":"https:\/\/www.kalkalaw.com\/es\/blog\/el-estatuto-de-muerte-por-negligencia-de-georgia-lo-que-las-familias-deben-saber\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kalkalaw.com\/es\/blog\/el-estatuto-de-muerte-por-negligencia-de-georgia-lo-que-las-familias-deben-saber\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kalkalaw.com\/es\/blog\/el-estatuto-de-muerte-por-negligencia-de-georgia-lo-que-las-familias-deben-saber\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kalkalaw.com\/es\/"},{"@type":"ListItem","position":2,"name":"El Estatuto de Muerte por Negligencia de Georgia: Lo que las familias deben saber"}]},{"@type":"WebSite","@id":"https:\/\/www.kalkalaw.com\/es\/#website","url":"https:\/\/www.kalkalaw.com\/es\/","name":"The Kalka Law Group - Personal Injury & Car Accident Attorneys","description":"","publisher":{"@id":"https:\/\/www.kalkalaw.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kalkalaw.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.kalkalaw.com\/es\/#organization","name":"The Kalka Law Group - Personal Injury & Car Accident Attorneys","url":"https:\/\/www.kalkalaw.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.kalkalaw.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.kalkalaw.com\/wp-content\/uploads\/2023\/10\/logo-navy.png","contentUrl":"https:\/\/www.kalkalaw.com\/wp-content\/uploads\/2023\/10\/logo-navy.png","width":1088,"height":364,"caption":"The Kalka Law Group - Personal Injury & Car Accident Attorneys"},"image":{"@id":"https:\/\/www.kalkalaw.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KalkaLawGroup\/","https:\/\/x.com\/KalkaLawGroup","https:\/\/www.avvo.com\/attorneys\/30309-ga-anthony-kalka-479261.html","https:\/\/www.yelp.com\/biz\/the-kalka-law-group-marietta","https:\/\/www.linkedin.com\/company\/kalkalawgroup\/"]},{"@type":"Person","@id":"https:\/\/www.kalkalaw.com\/es\/#\/schema\/person\/bcee12dd478c67036469886a7b9fdb26","name":"Kalka Law"}]}},"_links":{"self":[{"href":"https:\/\/www.kalkalaw.com\/es\/wp-json\/wp\/v2\/posts\/6340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kalkalaw.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kalkalaw.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kalkalaw.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kalkalaw.com\/es\/wp-json\/wp\/v2\/comments?post=6340"}],"version-history":[{"count":0,"href":"https:\/\/www.kalkalaw.com\/es\/wp-json\/wp\/v2\/posts\/6340\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kalkalaw.com\/es\/wp-json\/wp\/v2\/media?parent=6340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kalkalaw.com\/es\/wp-json\/wp\/v2\/categories?post=6340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kalkalaw.com\/es\/wp-json\/wp\/v2\/tags?post=6340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}